{"id":13437,"date":"2021-12-24T07:00:00","date_gmt":"2021-12-24T10:00:00","guid":{"rendered":"https:\/\/classnet.tech\/?p=13437"},"modified":"2021-12-24T07:00:00","modified_gmt":"2021-12-24T10:00:00","slug":"consultoria-em-lgpd-e-clinicas-de-estetica","status":"publish","type":"post","link":"https:\/\/mobcintra.com.br\/blog_classnet\/consultoria-em-lgpd-e-clinicas-de-estetica\/","title":{"rendered":"Consultoria em LGPD e Cl\u00ednicas de Est\u00e9tica"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A est\u00e9tica corporal atrai milhares de pessoas&nbsp;no Brasil para as cl\u00ednicas est\u00e9ticas de todos os tamanhos.&nbsp;Atualmente, cuidar do corpo faz com que uma pessoa pare\u00e7a&nbsp;mais&nbsp;10\/10, entretanto, esta arte j\u00e1 existe h\u00e1 s\u00e9culos.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A&nbsp;ess\u00eancia de cuidar do corpo \u00e9 uma das marcas hist\u00f3ricas da humanidade.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cada cl\u00ednica de est\u00e9tica \u00e9 \u00fanica e pode ser&nbsp;<a href=\"https:\/\/youtu.be\/LyEKyX6nSZM\">dados sens\u00edveis<\/a>&nbsp;dos clientes para os olhos da lei.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m da higiene, \u00e9 importante que o consumidor apenas fa\u00e7a esse servi\u00e7o em locais com alvar\u00e1 de funcionamento (os dados&nbsp;e a sua privacidade dos clientes devem estar protegidos).&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A qualquer momento, voc\u00ea pode revogar o consentimento e cl\u00ednica est\u00e9tica que fez a implementa\u00e7\u00e3o da LGPD tem o dever de dizer como os seus dados ser\u00e3o anonimizados ou exclu\u00eddos.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O significado de autocuidado \u00e9 relativo, j\u00e1 que algumas pessoas se preocupam com o que a imagem representa, com o significado do corpo, enquanto outras fazem a tratamentos est\u00e9ticos apenas por sua beleza (o que \u00e9 legitimo de todas as formas).&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por sua vez,&nbsp;a&nbsp;<a href=\"https:\/\/classnet.tech\/consultoria-lgpd\/\" target=\"_blank\" rel=\"noreferrer noopener\">LGPD (Lei Geral de Prote\u00e7\u00e3o de Dados Pessoais)<\/a>&nbsp;tem como objetivo a prote\u00e7\u00e3o de dados pessoais e regular o seu processo de coleta, transmiss\u00e3o e tratamento. Isso significa que&nbsp;as cl\u00ednicas est\u00e9ticas do Brasil&nbsp;dever\u00e3o se adequar \u00e0s novas regras imediatamente.\u202f&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quem quer fazer procedimentos est\u00e9ticos para o ver\u00e3o 2022, voce tem que se preocupar com a higiene, compet\u00eancia e com a privacidade! Sempre fa\u00e7a seus procedimentos em cl\u00ednicas s\u00e9rias, que atuam de acordo com a lei e respeitam o sigilo do cliente com&nbsp;<a href=\"https:\/\/classnet.tech\/compliance-digital\/\" target=\"_blank\" rel=\"noreferrer noopener\">compliance digital<\/a>.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A lei Geral de Prote\u00e7\u00e3o de Dados Pessoais j\u00e1 est\u00e1 em vigor. \u00c9 importante se apressar para come\u00e7ar a implanta\u00e7\u00e3o&nbsp;para a sua cl\u00ednica, n\u00e3o importando se ela \u00e9 pequena ou grande.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As multas ser\u00e3o impostas aos infratores a partir de 2022, entretanto, a preven\u00e7\u00e3o sempre sai mais barato do que a defesa de&nbsp;<a href=\"https:\/\/classnet.tech\/multa-de-ate-r-50-mi-sancoes-da-lgpd-comecam-a-valer\/\">autos de infra\u00e7\u00e3o milion\u00e1rios<\/a>.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Antes da LGPD,&nbsp;as cl\u00ednicas est\u00e9ticas&nbsp;eram livres para usar de forma indiscriminada dados de pessoas obtidos por cadastros em plataformas pr\u00f3prias ou por meio de capta\u00e7\u00e3o de leads, sejam de redes sociais ou base de terceiros.&nbsp;Muitas vezes coletavam autoriza\u00e7\u00f5es ilegais para uso perp\u00e9tuo da imagem do cliente \u2013 fato que \u00e9&nbsp;<a href=\"https:\/\/classnet.tech\/lgpd-nas-redes-sociais-o-que-voce-precisa-saber-para-nao-ser-multado\/\">totalmente ilegal<\/a>.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com a implementa\u00e7\u00e3o da lei, entrar\u00e1 em vigor uma regulamenta\u00e7\u00e3o determinando quando a empresa poder\u00e1 armazenar, processar e transferir esses dados, sempre com o consentimento do usu\u00e1rio, salvo exce\u00e7\u00f5es, como, dados pessoais tratados por pessoa f\u00edsica para fins exclusivamente pessoais ou para fins exclusivamente art\u00edsticos ou acad\u00eamicos.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quer saber se a sua cl\u00ednica est\u00e9tica est\u00e1 de acordo com a lei?&nbsp;N\u00e3o adianta fingir dem\u00eancia,&nbsp;voce&nbsp;est\u00e1 na mira da lei!&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/classnet.tech\/contato\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Entre em contato<\/strong><\/a><strong>&nbsp;<\/strong>e&nbsp;receba nosso e-book totalmente gr\u00e1tis!&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O que muda com a LGPD?&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>A lei determina que se uma empresa, seja ela virtual ou f\u00edsica, deseja obter consentimento do usu\u00e1rio ou cliente para realizar tratamento de dados pessoais, essa dever\u00e1 proporcionar clareza sobre o intuito<\/strong>, evitando que a cl\u00e1usula para o consentimento esteja nas entrelinhas ou no final de textos longos e ma\u00e7antes.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tamb\u00e9m dever\u00e1 se deixado claro ao usu\u00e1rio que ele est\u00e1 consentindo o tratamento de seus dados pessoais com o intuito de trabalhar a base de clientes de determinada empresa ou parceiros&nbsp;dos profissionais da cl\u00ednica est\u00e9tica.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O descumprimento da LGPD poder\u00e1 causar proibi\u00e7\u00e3o total ou parcial do tratamento de dados pela empresa, al\u00e9m de aplica\u00e7\u00e3o de multas, que poder\u00e3o chegar a 2% do faturamento di\u00e1rio ou R$50 milh\u00f5es, dependendo da gravidade da a\u00e7\u00e3o cometida.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>A&nbsp;Dra<\/strong><strong>.&nbsp;<\/strong><a href=\"http:\/\/lattes.cnpq.br\/9082103433523188\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Ana Paula Siqueira<\/strong><\/a><strong>&nbsp;\u00e9&nbsp;graduada em direito p\u00f3s-graduada em direito empresarial pela Universidade Mackenzie&nbsp;Mestre e Doutorando pela PUC\/SP em direito digital<\/strong>,&nbsp;professora, advogada e palestrante.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">21 anos de experi\u00eancia na consultoria em direito digital,&nbsp;compliance&nbsp;digital&nbsp;e em consultoria em LGPD&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como montar uma cl\u00ednica est\u00e9tica de sucesso?&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/classnet.tech\/contato\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Entre em contato<\/strong><\/a>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Para contratar&nbsp;a sua implementa\u00e7\u00e3o da LGPD na sua cl\u00ednica est\u00e9tica, entre em contato pelo link acima<\/strong>&nbsp;ou envie&nbsp;mensagens&nbsp;pelo WhatsApp.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se preferir, ligue para (11) 2384-1013 ou mande um e-mail para&nbsp;<a href=\"mailto:contato@slmadv.com.br\">contato@slmadv.com.br<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A est\u00e9tica corporal atrai milhares de pessoas&nbsp;no Brasil para as cl\u00ednicas est\u00e9ticas de todos os tamanhos.&nbsp;Atualmente, cuidar do corpo faz com que uma pessoa pare\u00e7a&nbsp;mais&nbsp;10\/10, entretanto, esta arte j\u00e1 existe h\u00e1 s\u00e9culos.&nbsp; A&nbsp;ess\u00eancia de cuidar do corpo \u00e9 uma das marcas hist\u00f3ricas da humanidade.&nbsp; Cada cl\u00ednica de est\u00e9tica \u00e9 \u00fanica e pode ser&nbsp;dados sens\u00edveis&nbsp;dos clientes [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":13499,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,12,18,23],"tags":[],"class_list":["post-13437","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-consultoria-lgpd","category-curso-lgpd","category-especialista-em-direito-digital","category-metodo-lgpd-blindado"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6.1 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Consultoria em LGPD e Cl\u00ednicas de Est\u00e9tica - Blog do Classnet.tech<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mobcintra.com.br\/blog_classnet\/consultoria-em-lgpd-e-clinicas-de-estetica\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Consultoria em LGPD e Cl\u00ednicas de Est\u00e9tica - Blog do Classnet.tech\" \/>\n<meta property=\"og:description\" content=\"A est\u00e9tica corporal atrai milhares de pessoas&nbsp;no Brasil para as cl\u00ednicas est\u00e9ticas de todos os tamanhos.&nbsp;Atualmente, cuidar do corpo faz com que uma pessoa pare\u00e7a&nbsp;mais&nbsp;10\/10, entretanto, esta arte j\u00e1 existe h\u00e1 s\u00e9culos.&nbsp; A&nbsp;ess\u00eancia de cuidar do corpo \u00e9 uma das marcas hist\u00f3ricas da humanidade.&nbsp; Cada cl\u00ednica de est\u00e9tica \u00e9 \u00fanica e pode ser&nbsp;dados sens\u00edveis&nbsp;dos clientes [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mobcintra.com.br\/blog_classnet\/consultoria-em-lgpd-e-clinicas-de-estetica\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog do Classnet.tech\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-24T10:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mobcintra.com.br\/blog_classnet\/wp-content\/uploads\/2021\/12\/correta-estetica.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"533\" \/>\n\t<meta property=\"og:image:height\" content=\"399\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"blog_classnet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"blog_classnet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/mobcintra.com.br\/blog_classnet\/consultoria-em-lgpd-e-clinicas-de-estetica\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/mobcintra.com.br\/blog_classnet\/consultoria-em-lgpd-e-clinicas-de-estetica\/\"},\"author\":{\"name\":\"blog_classnet\",\"@id\":\"https:\/\/mobcintra.com.br\/blog_classnet\/#\/schema\/person\/77513dd445767b9db8ad39386b2e0a97\"},\"headline\":\"Consultoria em LGPD e Cl\u00ednicas de Est\u00e9tica\",\"datePublished\":\"2021-12-24T10:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/mobcintra.com.br\/blog_classnet\/consultoria-em-lgpd-e-clinicas-de-estetica\/\"},\"wordCount\":812,\"image\":{\"@id\":\"https:\/\/mobcintra.com.br\/blog_classnet\/consultoria-em-lgpd-e-clinicas-de-estetica\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mobcintra.com.br\/blog_classnet\/wp-content\/uploads\/2021\/12\/correta-estetica.jpg\",\"articleSection\":[\"Consultoria LGPD\",\"Curso LGPD\",\"Especialista em Direito Digital\",\"M\u00e9todo LGPD Blindado\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mobcintra.com.br\/blog_classnet\/consultoria-em-lgpd-e-clinicas-de-estetica\/\",\"url\":\"https:\/\/mobcintra.com.br\/blog_classnet\/consultoria-em-lgpd-e-clinicas-de-estetica\/\",\"name\":\"Consultoria em LGPD e Cl\u00ednicas de Est\u00e9tica - Blog do Classnet.tech\",\"isPartOf\":{\"@id\":\"https:\/\/mobcintra.com.br\/blog_classnet\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/mobcintra.com.br\/blog_classnet\/consultoria-em-lgpd-e-clinicas-de-estetica\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/mobcintra.com.br\/blog_classnet\/consultoria-em-lgpd-e-clinicas-de-estetica\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mobcintra.com.br\/blog_classnet\/wp-content\/uploads\/2021\/12\/correta-estetica.jpg\",\"datePublished\":\"2021-12-24T10:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/mobcintra.com.br\/blog_classnet\/#\/schema\/person\/77513dd445767b9db8ad39386b2e0a97\"},\"breadcrumb\":{\"@id\":\"https:\/\/mobcintra.com.br\/blog_classnet\/consultoria-em-lgpd-e-clinicas-de-estetica\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mobcintra.com.br\/blog_classnet\/consultoria-em-lgpd-e-clinicas-de-estetica\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/mobcintra.com.br\/blog_classnet\/consultoria-em-lgpd-e-clinicas-de-estetica\/#primaryimage\",\"url\":\"https:\/\/mobcintra.com.br\/blog_classnet\/wp-content\/uploads\/2021\/12\/correta-estetica.jpg\",\"contentUrl\":\"https:\/\/mobcintra.com.br\/blog_classnet\/wp-content\/uploads\/2021\/12\/correta-estetica.jpg\",\"width\":533,\"height\":399},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mobcintra.com.br\/blog_classnet\/consultoria-em-lgpd-e-clinicas-de-estetica\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/mobcintra.com.br\/blog_classnet\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Consultoria em LGPD e Cl\u00ednicas de Est\u00e9tica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mobcintra.com.br\/blog_classnet\/#website\",\"url\":\"https:\/\/mobcintra.com.br\/blog_classnet\/\",\"name\":\"Blog do Classnet.tech\",\"description\":\"Informa\u00e7\u00f5es e not\u00edcias sobre CyberBullying, Consultoria LGPD e Cursos\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mobcintra.com.br\/blog_classnet\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/mobcintra.com.br\/blog_classnet\/#\/schema\/person\/77513dd445767b9db8ad39386b2e0a97\",\"name\":\"blog_classnet\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/240c4a5cef505f661da6b5dec4bc339f5a81f6b74670a7a64c31e7e52e6d8bff?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/240c4a5cef505f661da6b5dec4bc339f5a81f6b74670a7a64c31e7e52e6d8bff?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/240c4a5cef505f661da6b5dec4bc339f5a81f6b74670a7a64c31e7e52e6d8bff?s=96&d=mm&r=g\",\"caption\":\"blog_classnet\"},\"url\":\"https:\/\/mobcintra.com.br\/blog_classnet\/author\/blog_classnet\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Consultoria em LGPD e Cl\u00ednicas de Est\u00e9tica - Blog do Classnet.tech","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mobcintra.com.br\/blog_classnet\/consultoria-em-lgpd-e-clinicas-de-estetica\/","og_locale":"pt_BR","og_type":"article","og_title":"Consultoria em LGPD e Cl\u00ednicas de Est\u00e9tica - Blog do Classnet.tech","og_description":"A est\u00e9tica corporal atrai milhares de pessoas&nbsp;no Brasil para as cl\u00ednicas est\u00e9ticas de todos os tamanhos.&nbsp;Atualmente, cuidar do corpo faz com que uma pessoa pare\u00e7a&nbsp;mais&nbsp;10\/10, entretanto, esta arte j\u00e1 existe h\u00e1 s\u00e9culos.&nbsp; A&nbsp;ess\u00eancia de cuidar do corpo \u00e9 uma das marcas hist\u00f3ricas da humanidade.&nbsp; Cada cl\u00ednica de est\u00e9tica \u00e9 \u00fanica e pode ser&nbsp;dados sens\u00edveis&nbsp;dos clientes [&hellip;]","og_url":"https:\/\/mobcintra.com.br\/blog_classnet\/consultoria-em-lgpd-e-clinicas-de-estetica\/","og_site_name":"Blog do Classnet.tech","article_published_time":"2021-12-24T10:00:00+00:00","og_image":[{"width":533,"height":399,"url":"https:\/\/mobcintra.com.br\/blog_classnet\/wp-content\/uploads\/2021\/12\/correta-estetica.jpg","type":"image\/jpeg"}],"author":"blog_classnet","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"blog_classnet","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mobcintra.com.br\/blog_classnet\/consultoria-em-lgpd-e-clinicas-de-estetica\/#article","isPartOf":{"@id":"https:\/\/mobcintra.com.br\/blog_classnet\/consultoria-em-lgpd-e-clinicas-de-estetica\/"},"author":{"name":"blog_classnet","@id":"https:\/\/mobcintra.com.br\/blog_classnet\/#\/schema\/person\/77513dd445767b9db8ad39386b2e0a97"},"headline":"Consultoria em LGPD e Cl\u00ednicas de Est\u00e9tica","datePublished":"2021-12-24T10:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/mobcintra.com.br\/blog_classnet\/consultoria-em-lgpd-e-clinicas-de-estetica\/"},"wordCount":812,"image":{"@id":"https:\/\/mobcintra.com.br\/blog_classnet\/consultoria-em-lgpd-e-clinicas-de-estetica\/#primaryimage"},"thumbnailUrl":"https:\/\/mobcintra.com.br\/blog_classnet\/wp-content\/uploads\/2021\/12\/correta-estetica.jpg","articleSection":["Consultoria LGPD","Curso LGPD","Especialista em Direito Digital","M\u00e9todo LGPD Blindado"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/mobcintra.com.br\/blog_classnet\/consultoria-em-lgpd-e-clinicas-de-estetica\/","url":"https:\/\/mobcintra.com.br\/blog_classnet\/consultoria-em-lgpd-e-clinicas-de-estetica\/","name":"Consultoria em LGPD e Cl\u00ednicas de Est\u00e9tica - Blog do Classnet.tech","isPartOf":{"@id":"https:\/\/mobcintra.com.br\/blog_classnet\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mobcintra.com.br\/blog_classnet\/consultoria-em-lgpd-e-clinicas-de-estetica\/#primaryimage"},"image":{"@id":"https:\/\/mobcintra.com.br\/blog_classnet\/consultoria-em-lgpd-e-clinicas-de-estetica\/#primaryimage"},"thumbnailUrl":"https:\/\/mobcintra.com.br\/blog_classnet\/wp-content\/uploads\/2021\/12\/correta-estetica.jpg","datePublished":"2021-12-24T10:00:00+00:00","author":{"@id":"https:\/\/mobcintra.com.br\/blog_classnet\/#\/schema\/person\/77513dd445767b9db8ad39386b2e0a97"},"breadcrumb":{"@id":"https:\/\/mobcintra.com.br\/blog_classnet\/consultoria-em-lgpd-e-clinicas-de-estetica\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mobcintra.com.br\/blog_classnet\/consultoria-em-lgpd-e-clinicas-de-estetica\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/mobcintra.com.br\/blog_classnet\/consultoria-em-lgpd-e-clinicas-de-estetica\/#primaryimage","url":"https:\/\/mobcintra.com.br\/blog_classnet\/wp-content\/uploads\/2021\/12\/correta-estetica.jpg","contentUrl":"https:\/\/mobcintra.com.br\/blog_classnet\/wp-content\/uploads\/2021\/12\/correta-estetica.jpg","width":533,"height":399},{"@type":"BreadcrumbList","@id":"https:\/\/mobcintra.com.br\/blog_classnet\/consultoria-em-lgpd-e-clinicas-de-estetica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/mobcintra.com.br\/blog_classnet\/"},{"@type":"ListItem","position":2,"name":"Consultoria em LGPD e Cl\u00ednicas de Est\u00e9tica"}]},{"@type":"WebSite","@id":"https:\/\/mobcintra.com.br\/blog_classnet\/#website","url":"https:\/\/mobcintra.com.br\/blog_classnet\/","name":"Blog do Classnet.tech","description":"Informa\u00e7\u00f5es e not\u00edcias sobre CyberBullying, Consultoria LGPD e Cursos","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mobcintra.com.br\/blog_classnet\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/mobcintra.com.br\/blog_classnet\/#\/schema\/person\/77513dd445767b9db8ad39386b2e0a97","name":"blog_classnet","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/240c4a5cef505f661da6b5dec4bc339f5a81f6b74670a7a64c31e7e52e6d8bff?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/240c4a5cef505f661da6b5dec4bc339f5a81f6b74670a7a64c31e7e52e6d8bff?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/240c4a5cef505f661da6b5dec4bc339f5a81f6b74670a7a64c31e7e52e6d8bff?s=96&d=mm&r=g","caption":"blog_classnet"},"url":"https:\/\/mobcintra.com.br\/blog_classnet\/author\/blog_classnet\/"}]}},"_links":{"self":[{"href":"https:\/\/mobcintra.com.br\/blog_classnet\/wp-json\/wp\/v2\/posts\/13437","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mobcintra.com.br\/blog_classnet\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mobcintra.com.br\/blog_classnet\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mobcintra.com.br\/blog_classnet\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mobcintra.com.br\/blog_classnet\/wp-json\/wp\/v2\/comments?post=13437"}],"version-history":[{"count":0,"href":"https:\/\/mobcintra.com.br\/blog_classnet\/wp-json\/wp\/v2\/posts\/13437\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mobcintra.com.br\/blog_classnet\/wp-json\/wp\/v2\/media\/13499"}],"wp:attachment":[{"href":"https:\/\/mobcintra.com.br\/blog_classnet\/wp-json\/wp\/v2\/media?parent=13437"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mobcintra.com.br\/blog_classnet\/wp-json\/wp\/v2\/categories?post=13437"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mobcintra.com.br\/blog_classnet\/wp-json\/wp\/v2\/tags?post=13437"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}